{"id":4332,"date":"2026-07-01T10:43:45","date_gmt":"2026-07-01T13:43:45","guid":{"rendered":"https:\/\/web.sanjuan.gob.ar\/cultura\/?post_type=ajde_events&#038;p=4332"},"modified":"2026-07-01T10:43:47","modified_gmt":"2026-07-01T13:43:47","slug":"convocatoria-para-escuelas-para-moliendo-a-moliere","status":"publish","type":"ajde_events","link":"https:\/\/web.sanjuan.gob.ar\/cultura\/events\/convocatoria-para-escuelas-para-moliendo-a-moliere\/","title":{"rendered":"Convocatoria para escuelas para Moliendo a Moli\u00e8re"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como parte de su compromiso con la formaci\u00f3n cultural de las nuevas generaciones y la promoci\u00f3n del acceso al arte como herramienta de aprendizaje, reflexi\u00f3n y encuentro, el Teatro del Bicentenario, junto a Fundaci\u00f3n Banco San Juan, abre la convocatoria para que escuelas p\u00fablicas y privadas de toda la provincia participen de las funciones educativas gratuitas de Moliendo a Moli\u00e8re, una nueva producci\u00f3n realizada para acercar a estudiantes al universo de las artes esc\u00e9nicas.<br>El Teatro del Bicentenario, dependiente del Ministerio de Turismo, Cultura y Deporte, presenta Moliendo a Moli\u00e8re, una nueva producci\u00f3n que integra teatro, m\u00fasica y danza bajo la direcci\u00f3n de Emiliano Dionisi, inspirada en textos de Moli\u00e8re y en la m\u00fasica de Jean-Baptiste Lully y Marc-Antoine Charpentier.<br>La propuesta forma parte del Programa de Introducci\u00f3n al Arte para la Ni\u00f1ez y Adolescencia y se desarrolla en conjunto con la Fundaci\u00f3n Banco San Juan, a trav\u00e9s de su programa provincial \u201cCon la M\u00fasica a Otra Parte\u201d, fortaleciendo el v\u00ednculo entre cultura, educaci\u00f3n y comunidad, y generando oportunidades para que miles de estudiantes sanjuaninos accedan a experiencias art\u00edsticas de excelencia.<br>La obra presenta a una singular compa\u00f1\u00eda de artistas de dudosa reputaci\u00f3n que emprende una misi\u00f3n tan ambiciosa como desopilante: conquistar con su talento a la \u00fanica persona capaz de cambiar su destino, aun cuando para lograrlo deban llevar el enga\u00f1o hasta l\u00edmites impensados.<br>Con humor, m\u00fasica en vivo, actuaci\u00f3n y danza, Moliendo a Moli\u00e8re recupera el esp\u00edritu l\u00fadico y sat\u00edrico del gran dramaturgo franc\u00e9s e invita al p\u00fablico infantojuvenil a reflexionar sobre las apariencias, re\u00edrse de las conductas humanas y descubrir el teatro como un espacio de imaginaci\u00f3n, juego, encuentro y reflexi\u00f3n.<br>Esta producci\u00f3n reversionada es concebida y realizada por los equipos art\u00edsticos y t\u00e9cnicos del Teatro del Bicentenario, poniendo especialmente en valor el trabajo de sus talleres y \u00e1reas de producci\u00f3n, y reafirmando el compromiso institucional con el desarrollo de nuevos p\u00fablicos, la producci\u00f3n propia y el fortalecimiento de la realizaci\u00f3n local.<br>La convocatoria est\u00e1 dirigida a alumnos de 4\u00b0, 5\u00b0 y 6\u00b0 grado del Nivel Primario y 1\u00b0 y 2\u00b0 a\u00f1o del Nivel Secundario de escuelas e instituciones educativas p\u00fablicas y privadas de toda la provincia.<br>Funciones educativas gratuitas: Sala Principal del 14 al 18 de septiembre en horario de ma\u00f1ana y tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inscripciones abiertas: desde el 26 de junio hasta el 31 de julio. Cupos limitados.<br>Las escuelas interesadas deber\u00e1n completar el formulario de inscripci\u00f3n habilitado por el Teatro del Bicentenario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n y consultas: gestiondepublicotdb@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"author":44,"featured_media":4333,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"tags":[],"event_type":[],"event_type_2":[],"class_list":["post-4332","ajde_events","type-ajde_events","status-publish","has-post-thumbnail","hentry","event_location-teatro-del-bicentenario"],"acf":[],"_links":{"self":[{"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/ajde_events\/4332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/comments?post=4332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/media\/4333"}],"wp:attachment":[{"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/media?parent=4332"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/tags?post=4332"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/event_type?post=4332"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/web.sanjuan.gob.ar\/cultura\/wp-json\/wp\/v2\/event_type_2?post=4332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}